{
    "id": 11618,
    "date": "2019-10-22T09:36:35",
    "date_gmt": "2019-10-22T12:36:35",
    "guid": {
        "rendered": "https:\/\/www.hoteldelreyfoz.com\/?p=11618"
    },
    "modified": "2021-11-25T08:00:08",
    "modified_gmt": "2021-11-25T11:00:08",
    "slug": "historia-del-rey-quality-hotel",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/",
    "title": {
        "rendered": "Del Rey Quality Hotel: Conhe\u00e7a a Nossa Hist\u00f3ria"
    },
    "content": {
        "rendered": "<p>O <strong>Del Rey Quality Hotel<\/strong> passou por uma longa e linda jornada antes de se tornar conhecido e classificado como o <strong>6\u00ba melhor hotel do Brasil para fam\u00edlias<\/strong>.&nbsp;<\/p>\n\n\n\n<p>E para voc\u00ea que j\u00e1 se hospedou conosco, ou pretende passar um tempo com a gente, gostar\u00edamos de compartilhar um pouco da<strong> nossa hist\u00f3ria<\/strong>, para que voc\u00ea possa entender e fazer parte dessa fam\u00edlia. Confira:<\/p>\n\n\n\n<!--more-->\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-flat ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Confira no artigo:<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/#A-Historia-Antes-do-Hotel\" >A Hist\u00f3ria Antes do Hotel<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/#A-Fundacao-do-Del-Rey-Quality-Hotel\" >A Funda\u00e7\u00e3o do Del Rey Quality Hotel<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/#O-Hotel-Atualmente\" >O Hotel Atualmente<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A-Historia-Antes-do-Hotel\"><\/span>A Hist\u00f3ria Antes do Hotel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Antes morador de Portugal, <strong>Jaime Ant\u00f4nio da Costa Mendes <\/strong><em>(in memoriam)<\/em> chegou ao Brasil em dezembro de 1950. Durante a inf\u00e2ncia, trabalhou com o pai no Hotel F\u00e1tima, na cidade de Maring\u00e1, no Paran\u00e1.<\/p>\n\n\n\n<p>Durante esse per\u00edodo em que trabalhou com o pai, Jaime Mendes aprendeu muitas fun\u00e7\u00f5es no <strong>ramo hoteleiro<\/strong> e veio para Foz do Igua\u00e7u no ano de 1968, acabando por trabalhar como <strong>recepcionista e guia de turismo<\/strong> na cidade.<\/p>\n\n\n\n<p>Em 1973, Jaime Mendes conheceu sua futura esposa. <strong>Maria Francisca Machado Mendes<\/strong> veio para a cidade com uma excurs\u00e3o da faculdade da Universidade Estadual de Goi\u00e1s e acabou ficando <strong>hospedada no mesmo hotel<\/strong> em que ele trabalhava.<\/p>\n\n\n\n<p>Ap\u00f3s o final da excurs\u00e3o, ambos trocaram cartas<strong> <\/strong>por seis meses antes de se casar. Ao mudar para Foz do Igua\u00e7u, Maria Mendes come\u00e7ou a <strong>trabalhar no ramo da hotelaria<\/strong> com seu marido e, <strong>apenas em 1976<\/strong> ambos deram entrada em um pr\u00e9dio na Avenida Brasil para come\u00e7ar o primeiro hotel.<\/p>\n\n\n\n<p>Alguns anos mais tarde, o Sr. Jaime teve a oportunidade de trabalhar no Hotel das Cataratas, aproveitando este caminho para <strong>aprimorar seus conhecimentos em hotelaria<\/strong>. Por fim, ele e sua esposa decidiram que era hora de construir seu pr\u00f3prio neg\u00f3cio, abrindo o <strong>Hotel Del Rey Quality Hotel<\/strong> <strong>em 1985<\/strong>.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A-Fundacao-do-Del-Rey-Quality-Hotel\"><\/span> A Funda\u00e7\u00e3o do Del Rey Quality Hotel <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.hoteldelreyfoz.com\/wp-content\/uploads\/2019\/10\/Jaime-Mendes-fundador-do-Del-Rey-Quality-Hotel-1170x638.png\" alt=\"Jaime Mendes, fundador do Del Rey Quality Hotel\" class=\"wp-image-11621\"\/><\/figure>\n\n\n\n<p>O <strong>Del Rey Quality Hotel<\/strong> &#8211; antes conhecido como <strong>Hotel Del Rey Foz &#8211;<\/strong> foi fundado pelo Sr. Jaime Ant\u00f4nio da Costa Mendes em 1985, quando as cotas no Paraguai foram liberadas e as pessoas viajavam bastante para Foz para fazer compras do outro lado da fronteira.<\/p>\n\n\n\n<p>O nome \u2018<strong>Del Rey<\/strong>\u2019 foi escolhido, pois o hotel era inspirado no <strong>tratamento da realeza<\/strong> e, desde o in\u00edcio tinha o objetivo de tratar os h\u00f3spedes como se fossem \u2018Reis\u2019 e \u2018Rainhas\u2019.<\/p>\n\n\n\n<p>A princ\u00edpio, ap\u00f3s o terreno onde ficaria localizado o <strong>Del Rey Quality Hotel<\/strong> ter sido comprado, foram constru\u00eddos apenas 22 apartamentos. Mas, com o sucesso do empreendimento, em 1989 foi realizada a <strong>primeira amplia\u00e7\u00e3o no hotel<\/strong> &#8211; gra\u00e7as \u00e0 compra do terreno ao lado &#8211; onde foram constru\u00eddos mais 32 apartamentos, <strong>piscina<\/strong> e bar no terra\u00e7o.<br>Em 1992, o Del Rey em Foz passou por mais uma reforma para a renova\u00e7\u00e3o das instala\u00e7\u00f5es, o acr\u00e9scimo de uma <strong>sala de jogos<\/strong>, a constru\u00e7\u00e3o da capela e mais apartamentos novos. <\/p>\n\n\n\n<p><strong>&gt;&gt; Veja tamb\u00e9m: <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/hotel-del-rey-foz-atendimento-personalizado\/\" target=\"_blank\">Por que o Del Rey Quality Hotel \u00e9 o Hotel Ideal para Voc\u00ea?<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O-Hotel-Atualmente\"><\/span>O Hotel Atualmente<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Atualmente, a dire\u00e7\u00e3o do <strong>Del Rey Quality Hotel<\/strong> est\u00e1 sob o comando do Jaime, filho do casal fundador, que continua o legado do pai com muito esfor\u00e7o e dedica\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Hoje, o <strong>Del Rey Quality Hotel <\/strong>conta com 91 apartamentos estruturados para receber fam\u00edlias, amigos, pessoas que estejam viajando sozinhas ou a trabalho.<\/p>\n\n\n\n<p>Ao longo dos anos, recebemos muitos pr\u00eamios, como:<\/p>\n\n\n\n<ul><li>O <strong>6\u00ba melhor hotel do Brasil para fam\u00edlias<\/strong> pelo TripAdvisor<\/li><li><strong>Certificado de 3 estrelas<\/strong> do Minist\u00e9rio do Turismo<\/li><li>Um dos <strong>25 melhores hot\u00e9is da Am\u00e9rica Latina para Fam\u00edlia<\/strong> pelo TripAdvisor<\/li><li><strong>Pr\u00eamio Qualidade do Turismo do Paran\u00e1<\/strong> (2018-2019) concedido pelo SEBRAE<\/li><\/ul>\n\n\n\n<p>Vale lembrar que o hotel fica em uma localiza\u00e7\u00e3o privilegiada <strong>no centro de Foz do Igua\u00e7u<\/strong>, pertinho do Terminal de Transporte Urbano (TTU). Al\u00e9m de ser pr\u00f3ximo de mercado, padaria, farm\u00e1cias e muitas lojas.&nbsp;<\/p>\n\n\n\n<p>Disponibilizamos um <strong>servi\u00e7o de caf\u00e9 da manh\u00e3<\/strong> &#8211; servido a partir das 3h da manh\u00e3 &#8211; com mais de 85 itens que v\u00e3o desde p\u00e3es e bolos at\u00e9 tortas t\u00edpicas da tr\u00edplice fronteira.<\/p>\n\n\n\n<p>Para a parte de lazer, contamos com uma piscina e bar no terra\u00e7o, e uma sala de jogos com <strong>mesa de sinuca, pebolim e videogame<\/strong> para quem trouxer a fam\u00edlia e os filhos pequenos.<\/p>\n\n\n\n<p>Al\u00e9m disso, o <strong>Del Rey Quality<\/strong> <strong>Hotel<\/strong> tamb\u00e9m se preocupa com o meio ambiente e, por isso, utilizamos produtos biodegrad\u00e1veis, trabalhamos com reciclagem &#8211; separando mais de 200 quilos de material por semana -, possu\u00edmos sistemas de <strong>energias renov\u00e1veis<\/strong> &#8211; como placas solares &#8211; e evitamos utilizar embalagens pl\u00e1sticas, por isso os banheiros dos apartamentos s\u00e3o equipados com dispensers de shampoo e condicionador.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.hoteldelreyfoz.com\/wp-content\/uploads\/2019\/10\/Fachada-atual-do-Del-Rey-Quality-Hotel-1170x832.jpg\" alt=\"Fachada atual do Del Rey Quality Hotel\" data-id=\"11622\" class=\"wp-image-11622\"\/><\/figure><\/li><\/ul>\n\n\n\n<p>O <strong>Del Rey Quality Hotel<\/strong> busca sempre melhorar e fazer o m\u00e1ximo para cumprir a premissa de atender aos nossos clientes como \u2018reis\u2019 e \u2018rainhas\u2019. Por isso, <strong>estamos sempre em constante evolu\u00e7\u00e3o e melhorias para tornar a sua experi\u00eancia conosco inesquec\u00edvel!<\/strong><br><\/p>\n\n\n\n<p><strong>Quer fazer parte da nossa hist\u00f3ria e vivenciar tudo o que temos para oferecer? <a rel=\"noreferrer noopener\" label=\" (abre numa nova aba)\" href=\"https:\/\/myreservations.omnibees.com\/default.aspx?q=2694&amp;lang=pt-BR&amp;CheckIn=&amp;CheckOut=&amp;ad=1&amp;ch=0\" target=\"_blank\">Reserve agora sua hospedagem conosco e ganhe 10% de desconto!<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">Imagens: Arquivo Del Rey Quality Hotel<\/p>\n\n\n\n<p><\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>O Del Rey Quality Hotel passou por uma longa e linda jornada antes de se tornar conhecido e classificado como o 6\u00ba melhor hotel do Brasil para fam\u00edlias.&nbsp; E para voc\u00ea que j\u00e1 se hospedou conosco, ou pretende passar um tempo com a gente, gostar\u00edamos de compartilhar um pouco da nossa hist\u00f3ria, para que voc\u00ea [&hellip;]<\/p>",
        "protected": false
    },
    "author": 2,
    "featured_media": 11619,
    "comment_status": "open",
    "ping_status": "open",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "footnotes": ""
    },
    "categories": [
        193
    ],
    "tags": [
        278,
        96
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz<\/title>\n<meta name=\"description\" content=\"A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz\" \/>\n<meta property=\"og:description\" content=\"A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Del Rey Quality Hotel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/delreyfozhotel\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T12:36:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T11:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hoteldelreyfoz.com\/wp-content\/uploads\/2019\/10\/fachada-del-rey-quality-hotel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jaime Mendes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/\"},\"author\":{\"name\":\"Jaime Mendes\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#\/schema\/person\/7ea55b17cae3e4b8de28d979ce955c9b\"},\"headline\":\"Del Rey Quality Hotel: Conhe\u00e7a a Nossa Hist\u00f3ria\",\"datePublished\":\"2019-10-22T12:36:35+00:00\",\"dateModified\":\"2021-11-25T11:00:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#organization\"},\"keywords\":[\"del rey hotel\",\"hotel del rey foz\"],\"articleSection\":[\"O Hotel\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/\",\"url\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/\",\"name\":\"Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz\",\"isPartOf\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#website\"},\"datePublished\":\"2019-10-22T12:36:35+00:00\",\"dateModified\":\"2021-11-25T11:00:08+00:00\",\"description\":\"A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.hoteldelreyfoz.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del Rey Quality Hotel: Conhe\u00e7a a Nossa Hist\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#website\",\"url\":\"https:\/\/www.hoteldelreyfoz.com\/\",\"name\":\"Del Rey Quality Hotel\",\"description\":\"Hotel em Foz do Igua\u00e7u com pre\u00e7os acess\u00edveis, quartos amplos e localiza\u00e7\u00e3o no Centro, perto de tudo. Reserve pelo nosso site com desconto!\",\"publisher\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hoteldelreyfoz.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#organization\",\"name\":\"Del Rey Quality Hotel\",\"url\":\"https:\/\/www.hoteldelreyfoz.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hoteldelreyfoz.com.br\/wp-content\/uploads\/2021\/09\/delrey.png\",\"contentUrl\":\"https:\/\/www.hoteldelreyfoz.com.br\/wp-content\/uploads\/2021\/09\/delrey.png\",\"width\":225,\"height\":224,\"caption\":\"Del Rey Quality Hotel\"},\"image\":{\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/delreyfozhotel\",\"https:\/\/www.instagram.com\/delreyfoz\/\",\"https:\/\/www.youtube.com\/channel\/UCSBntO46TaFRFMvuxjJBS_w\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hoteldelreyfoz.com\/#\/schema\/person\/7ea55b17cae3e4b8de28d979ce955c9b\",\"name\":\"Jaime Mendes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz",
        "description": "A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/",
        "og_locale": "pt_BR",
        "og_type": "article",
        "og_title": "Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz",
        "og_description": "A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!",
        "og_url": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/blog\/historia-del-rey-quality-hotel\/",
        "og_site_name": "Del Rey Quality Hotel",
        "article_publisher": "https:\/\/www.facebook.com\/delreyfozhotel",
        "article_published_time": "2019-10-22T12:36:35+00:00",
        "article_modified_time": "2021-11-25T11:00:08+00:00",
        "og_image": [
            {
                "width": 1200,
                "height": 634,
                "url": "https:\/\/www.hoteldelreyfoz.com\/wp-content\/uploads\/2019\/10\/fachada-del-rey-quality-hotel.png",
                "type": "image\/png"
            }
        ],
        "author": "Jaime Mendes",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Escrito por": false,
            "Est. tempo de leitura": "4 minutos"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "Article",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#article",
                    "isPartOf": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/"
                    },
                    "author": {
                        "name": "Jaime Mendes",
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#\/schema\/person\/7ea55b17cae3e4b8de28d979ce955c9b"
                    },
                    "headline": "Del Rey Quality Hotel: Conhe\u00e7a a Nossa Hist\u00f3ria",
                    "datePublished": "2019-10-22T12:36:35+00:00",
                    "dateModified": "2021-11-25T11:00:08+00:00",
                    "mainEntityOfPage": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/"
                    },
                    "wordCount": 872,
                    "commentCount": 0,
                    "publisher": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#organization"
                    },
                    "keywords": [
                        "del rey hotel",
                        "hotel del rey foz"
                    ],
                    "articleSection": [
                        "O Hotel"
                    ],
                    "inLanguage": "pt-BR"
                },
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/",
                    "url": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/",
                    "name": "Del Rey Quality Hotel: Conhe\u00e7a Nossa Hist\u00f3ria | Blog Del Rey Foz",
                    "isPartOf": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#website"
                    },
                    "datePublished": "2019-10-22T12:36:35+00:00",
                    "dateModified": "2021-11-25T11:00:08+00:00",
                    "description": "A hist\u00f3ria do Hotel Del Rey Foz come\u00e7ou h\u00e1 34 anos, antes mesmo do fundador, Jaime Mendes, morar em Foz do Igua\u00e7u. Conhe\u00e7a um pouco mais sobre nossa trajet\u00f3ria!",
                    "breadcrumb": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#breadcrumb"
                    },
                    "inLanguage": "pt-BR",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/blog\/historia-del-rey-quality-hotel\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "In\u00edcio",
                            "item": "https:\/\/www.hoteldelreyfoz.com\/en\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Del Rey Quality Hotel: Conhe\u00e7a a Nossa Hist\u00f3ria"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/#website",
                    "url": "https:\/\/www.hoteldelreyfoz.com\/",
                    "name": "Del Rey Quality Hotel",
                    "description": "Hotel em Foz do Igua\u00e7u com pre\u00e7os acess\u00edveis, quartos amplos e localiza\u00e7\u00e3o no Centro, perto de tudo. Reserve pelo nosso site com desconto!",
                    "publisher": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/www.hoteldelreyfoz.com\/?s={search_term_string}"
                            },
                            "query-input": "required name=search_term_string"
                        }
                    ],
                    "inLanguage": "pt-BR"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/#organization",
                    "name": "Del Rey Quality Hotel",
                    "url": "https:\/\/www.hoteldelreyfoz.com\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "pt-BR",
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/www.hoteldelreyfoz.com.br\/wp-content\/uploads\/2021\/09\/delrey.png",
                        "contentUrl": "https:\/\/www.hoteldelreyfoz.com.br\/wp-content\/uploads\/2021\/09\/delrey.png",
                        "width": 225,
                        "height": 224,
                        "caption": "Del Rey Quality Hotel"
                    },
                    "image": {
                        "@id": "https:\/\/www.hoteldelreyfoz.com\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/delreyfozhotel",
                        "https:\/\/www.instagram.com\/delreyfoz\/",
                        "https:\/\/www.youtube.com\/channel\/UCSBntO46TaFRFMvuxjJBS_w"
                    ]
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/www.hoteldelreyfoz.com\/#\/schema\/person\/7ea55b17cae3e4b8de28d979ce955c9b",
                    "name": "Jaime Mendes"
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/posts\/11618"
            }
        ],
        "collection": [
            {
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/users\/2"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/comments?post=11618"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/posts\/11618\/revisions"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/media\/11619"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/media?parent=11618"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/categories?post=11618"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/www.hoteldelreyfoz.com\/pt_br\/wp-json\/wp\/v2\/tags?post=11618"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}